{"id":798,"date":"2022-04-11T10:53:21","date_gmt":"2022-04-11T10:53:21","guid":{"rendered":"https:\/\/openthinclient.com\/?page_id=798"},"modified":"2024-04-24T12:07:09","modified_gmt":"2024-04-24T12:07:09","slug":"jobs","status":"publish","type":"page","link":"https:\/\/openthinclient.com\/fr\/jobs\/","title":{"rendered":"Emplois"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"798\" class=\"elementor elementor-798\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64e744b0 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"64e744b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15dc1f23\" data-id=\"15dc1f23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0df083 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-hidden-phone elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1c0df083\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+49 711 1378636-0<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@openthinclient.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mo - Fr: 9:00 - 18:00<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d58c30e\" data-id=\"d58c30e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d98280c e-grid-align-right elementor-shape-square e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"4d98280c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-5646027\" href=\"https:\/\/de-de.facebook.com\/people\/openthinclient-gmbh\/100063657666030\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-7c2bcc0\" href=\"https:\/\/www.instagram.com\/openthinclient\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-2205e9e\" href=\"https:\/\/de.linkedin.com\/company\/openthinclient-gmbh\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-4b27cd1\" href=\"https:\/\/www.youtube.com\/openthinclient%20gmbh\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-278dfdab elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"278dfdab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-74d9cb0d\" data-id=\"74d9cb0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d5b9215 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"2d5b9215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1523\" height=\"235\" src=\"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-600x93.png\" class=\"attachment-full size-full wp-image-6230\" alt=\"openthinclient Logo\" srcset=\"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient.png 1523w, https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-300x46.png 300w, https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-1024x158.png 1024w, https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-768x119.png 768w, https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-18x3.png 18w, https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient-600x93.png 600w\" sizes=\"(max-width: 1523px) 100vw, 1523px\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1491a8\" data-id=\"c1491a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4338797d elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"4338797d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-slide\">\n\t\t\t\t<ul id=\"menu-1-4338797d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-8814\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-software\/\" class=\"elementor-item menu-link\">ThinClient Software<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29346\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software\/\" class=\"elementor-sub-item menu-link\">Branchen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-35100\"><a href=\"https:\/\/openthinclient.com\/fr\/case-studies\/\" class=\"elementor-sub-item menu-link\">Case Studies<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29340\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" class=\"elementor-sub-item menu-link\">Preise<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-32879\"><a href=\"https:\/\/openthinclient.com\/fr\/produkt\/openthinclient-dienstleistungspakete\/\" class=\"elementor-sub-item menu-link\">Dienstleistung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-29341\"><a href=\"https:\/\/openthinclient.com\/fr\/produkt\/openthinclient-management-server\/\" class=\"elementor-sub-item menu-link\">Kostenfrei testen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-8972\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware\/\" class=\"elementor-item menu-link\">ThinClient Hardware<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29350\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware\/\" class=\"elementor-sub-item menu-link\">Branchen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29348\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware-vergleich\/\" class=\"elementor-sub-item menu-link\">Ger\u00e4te<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32293\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-zubehoer\/\" class=\"elementor-sub-item menu-link\">Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34429\"><a href=\"https:\/\/docs.openthinclient.com\/\" class=\"elementor-item menu-link\">Dokumentation<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-8283\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/hilfe-faqs\/\" class=\"elementor-item menu-link\">Service<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1474\"><a href=\"https:\/\/openthinclient.com\/fr\/hilfe-faqs\/\" class=\"elementor-sub-item menu-link\">Hilfe &#038; FAQ\u00b4s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-810\"><a href=\"https:\/\/openthinclient.com\/fr\/professioneller-support\/\" class=\"elementor-sub-item menu-link\">Support<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/openthinclient.com\/fr\/community-wiki\/\" class=\"elementor-sub-item menu-link\">Dokumentation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5109\"><a href=\"https:\/\/openthinclient.com\/fr\/reklamation\/\" class=\"elementor-sub-item menu-link\">Reklamation<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-8284\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/ueber-uns\/\" class=\"elementor-item menu-link\">Firma<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-113\"><a href=\"https:\/\/openthinclient.com\/fr\/kontakt\/\" class=\"elementor-sub-item menu-link\">Kontakt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/openthinclient.com\/fr\/ueber-uns\/\" class=\"elementor-sub-item menu-link\">\u00dcber uns<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33847\"><a href=\"https:\/\/openthinclient.com\/fr\/jobs\/\" class=\"elementor-sub-item menu-link\">Jobs<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8802\"><a href=\"https:\/\/openthinclient.com\/fr\/mein-konto\/\" class=\"elementor-item menu-link\"><i style=\"font-size:1em;color:#0070b1\" class=\"wpmi__icon wpmi__label-1 wpmi__position-before wpmi__align-middle wpmi__size-1 fa fa-user\"><\/i><\/a><\/li>\n<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children menu-item-35174\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor menu-link\"><i style=\"font-size:1em;color:#0071b5\" class=\"wpmi__icon wpmi__label-1 wpmi__position-before wpmi__align-middle wpmi__size-1 fa fa-globe\"><\/i><span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-35176\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/de_DE.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to German\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35175\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/en_US.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to English\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35201\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/es_ES.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to Spanish\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35209\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/it_IT.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to Italian\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item wpmenucart wpmenucartli wpmenucart-display-standard menu-item wp-block-navigation-item wp-block-navigation-link menu-item-has-children has-child open-on-hover-click wp-block-navigation-submenu empty\" style=\"\">\n\t\n\t\n\t<a class=\"wpmenucart-contents empty-wpmenucart-visible wp-block-navigation-item__content\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" title=\"Commencez vos achats\">\n\t\t<i class=\"wpmenucart-icon-shopping-cart-2\" role=\"img\" aria-label=\"Panier\"><\/i>\n\t<\/a>\n\t\n\t\n\t<ul class=\"sub-menu wpmenucart empty wp-block-navigation__submenu-container\" style=\"\">\n\t\t\n\t\t\n\t\t<li class=\"menu-item wpmenucart-submenu-item clearfix wp-block-navigation-item wp-block-navigation-link empty-cart\">\n\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" class=\"clearfix wp-block-navigation-item__content\">\n\t\t\t\tvotre panier est actuellement vide\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\n\t\t\n\t<\/ul>\n\t\n\t\n<\/li><\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-4338797d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-8814\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-software\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">ThinClient Software<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29346\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Branchen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-35100\"><a href=\"https:\/\/openthinclient.com\/fr\/case-studies\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Case Studies<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29340\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Preise<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-32879\"><a href=\"https:\/\/openthinclient.com\/fr\/produkt\/openthinclient-dienstleistungspakete\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Dienstleistung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-29341\"><a href=\"https:\/\/openthinclient.com\/fr\/produkt\/openthinclient-management-server\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Kostenfrei testen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-8972\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">ThinClient Hardware<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29350\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Branchen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-29348\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-hardware-vergleich\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Ger\u00e4te<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-32293\"><a href=\"https:\/\/openthinclient.com\/fr\/thin-client-zubehoer\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Zubeh\u00f6r<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-34429\"><a href=\"https:\/\/docs.openthinclient.com\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Dokumentation<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-8283\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/hilfe-faqs\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Service<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1474\"><a href=\"https:\/\/openthinclient.com\/fr\/hilfe-faqs\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Hilfe &#038; FAQ\u00b4s<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-810\"><a href=\"https:\/\/openthinclient.com\/fr\/professioneller-support\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Support<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/openthinclient.com\/fr\/community-wiki\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Dokumentation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5109\"><a href=\"https:\/\/openthinclient.com\/fr\/reklamation\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Reklamation<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-8284\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/ueber-uns\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Firma<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-113\"><a href=\"https:\/\/openthinclient.com\/fr\/kontakt\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Kontakt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/openthinclient.com\/fr\/ueber-uns\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">\u00dcber uns<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33847\"><a href=\"https:\/\/openthinclient.com\/fr\/jobs\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Jobs<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8802\"><a href=\"https:\/\/openthinclient.com\/fr\/mein-konto\/\" class=\"elementor-item menu-link\" tabindex=\"-1\"><i style=\"font-size:1em;color:#0070b1\" class=\"wpmi__icon wpmi__label-1 wpmi__position-before wpmi__align-middle wpmi__size-1 fa fa-user\"><\/i><\/a><\/li>\n<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children menu-item-35174\"><a aria-expanded=\"false\" href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\"><i style=\"font-size:1em;color:#0071b5\" class=\"wpmi__icon wpmi__label-1 wpmi__position-before wpmi__align-middle wpmi__size-1 fa fa-globe\"><\/i><span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop current-language-menu-item menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-35176\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/de_DE.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to German\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35175\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/en_US.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to English\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35201\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/es_ES.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to Spanish\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n\t<li class=\"trp-language-switcher-container trp-menu-ls-item trp-menu-ls-desktop menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-35209\"><a href=\"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span class=\"trp-menu-ls-label\" data-no-translation title=\"\"><img loading=\"lazy\" src=\"https:\/\/openthinclient.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/flags\/1x1\/it_IT.svg\" class=\"trp-flag-image trp-flag-rounded\" alt=\"Change language to Italian\" loading=\"lazy\" decoding=\"async\" width=\"18\" height=\"14\" \/><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item wpmenucart wpmenucartli wpmenucart-display-standard menu-item wp-block-navigation-item wp-block-navigation-link menu-item-has-children has-child open-on-hover-click wp-block-navigation-submenu empty\" style=\"\">\n\t\n\t\n\t<a class=\"wpmenucart-contents empty-wpmenucart-visible wp-block-navigation-item__content\" href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" title=\"Commencez vos achats\">\n\t\t<i class=\"wpmenucart-icon-shopping-cart-2\" role=\"img\" aria-label=\"Panier\"><\/i>\n\t<\/a>\n\t\n\t\n\t<ul class=\"sub-menu wpmenucart empty wp-block-navigation__submenu-container\" style=\"\">\n\t\t\n\t\t\n\t\t<li class=\"menu-item wpmenucart-submenu-item clearfix wp-block-navigation-item wp-block-navigation-link empty-cart\">\n\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/thin-client-software-vergleich\/\" class=\"clearfix wp-block-navigation-item__content\">\n\t\t\t\tvotre panier est actuellement vide\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t\n\t\t\n\t<\/ul>\n\t\n\t\n<\/li><\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4a07e019 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"4a07e019\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-149eb195 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"149eb195\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-767c460e\" data-id=\"767c460e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1335edb8 elementor-widget elementor-widget-heading\" data-id=\"1335edb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Jobs<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7572459 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7572459\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44298d27\" data-id=\"44298d27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7342cd4e elementor-widget elementor-widget-toggle\" data-id=\"7342cd4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1931\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1931\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Softwareentwickler (m\/w\/d)<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1931\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1931\"><p><b><br \/>Ihre Aufgaben<\/b><\/p><ul><li>Pflege der Distribution &#8222;openthinclient-OS&#8220; basierend auf Debian<\/li><li>Administration der Buildsysteme<\/li><li>Aktive Teilnahme an der Planung der Software-Entwicklung<\/li><\/ul><p><b>Ihr Profil<\/b><\/p><ul><li>Erfahrung in der Softwareentwicklung<\/li><li>Praktische Erfahrungen mit <b>Linux <\/b>und <b>Python<\/b><\/li><li>Grundkenntnisse in der Administration von Netzwerken und CI-Plattform<\/li><\/ul><p><b>W\u00fcnschenswert<\/b><\/p><ul><li>Erfahrung in agiler Softwareentwicklung (SCRUM)<\/li><li>Erfahrung mit Citrix und RDP<\/li><li>Kenntnisse in UX-Design<\/li><li>Erfahrungen mit Ticketsystem, Wiki<\/li><\/ul><p><b>Wir bieten Ihnen<\/b><\/p><ul><li>Teilzeit oder Vollzeit<\/li><li>Homeoffice bzw. Hybrid m\u00f6glich<\/li><li>Eigenverantwortliches Arbeiten<\/li><li>Flexible Gestaltung der Arbeitszeit<\/li><li>kurze Entscheidungswege<\/li><li>Aus- und Weiterbildungen<\/li><li>sehr gute Sozialleistungen z.B. Fahrtkostenzuschuss usw.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-007b37f\" data-id=\"007b37f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-610c890 elementor-widget elementor-widget-toggle\" data-id=\"610c890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Second-Level-Support (m\/w\/d)<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1011\"><p><b><br \/>Ihre Aufgaben<\/b><\/p><ul><li>Technische Anfragen bearbeiten<\/li><li>L\u00f6sungen f\u00fcr spezifische Probleme finden<\/li><\/ul><p><b>Ihr Profil<\/b><\/p><ul><li><span class=\"css-sfm6zc e1wnkr790\" role=\"document\">Ausgepr\u00e4gte Linux-Kenntnisse<\/span><\/li><li>Kenntnisse in der Administration von Netzwerken<\/li><\/ul><p><b>W\u00fcnschenswert<\/b><\/p><ul><li>Erfahrungen mit Thin Clients<\/li><li>Erfahrung mit VDI-Umgebungen <\/li><li>Erfahrung mit Netzwerktechnologien <\/li><\/ul><p><b>Wir bieten Ihnen<\/b><\/p><ul><li>Teilzeit oder Vollzeit<\/li><li>Homeoffice bzw. Hybrid m\u00f6glich<\/li><li>Eigenverantwortliches Arbeiten<\/li><li>Flexible Gestaltung der Arbeitszeit<\/li><li>kurze Entscheidungswege<\/li><li>Aus- und Weiterbildungen<\/li><li>sehr gute Sozialleistungen z.B. Fahrtkostenzuschuss usw.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15f2792 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15f2792\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c1de99\" data-id=\"9c1de99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bc0974 elementor-widget elementor-widget-text-editor\" data-id=\"7bc0974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"css-sfm6zc e1wnkr790\" role=\"document\">Erkennen Sie sich in dieser Stellenausschreibung wieder und f\u00fchlen sich von dem Aufgabengebiet angesprochen, dann freuen wir uns auf Ihre aussagekr\u00e4ftigen und vollst\u00e4ndigen Bewerbungsunterlagen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a69f081 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a69f081\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3b0279\" data-id=\"b3b0279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-678af19 elementor-button-align-start elementor-widget elementor-widget-form\" data-id=\"678af19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;N\\u00e4chster&quot;,&quot;step_previous_label&quot;:&quot;Voriger&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Neue Bewerbung\" aria-label=\"Neue Bewerbung\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"798\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"678af19\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Jobs - openthinclient\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"798\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVorname\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Vorname\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_25fbc7d elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_25fbc7d\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_25fbc7d]\" id=\"form-field-field_25fbc7d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-Mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_c5fd2de elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_c5fd2de\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tBewerbung als\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_c5fd2de]\" id=\"form-field-field_c5fd2de\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"Softwareentwickler (m\/w\/d)\">Softwareentwickler (m\/w\/d)<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Second-Level-Support (m\/w\/d)\">Second-Level-Support (m\/w\/d)<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_5c0ed90 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5c0ed90\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tBewerbungsunterlagen\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_5c0ed90][]\" id=\"form-field-field_5c0ed90\" class=\"elementor-field elementor-size-sm  elementor-upload-field\" required=\"required\" multiple=\"multiple\" data-maxsize=\"10\" data-maxsize-message=\"Diese Datei \u00fcbersteigt die maximale Dateigr\u00f6\u00dfe.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm elementor-animation-wobble-horizontal\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Bewerbung absenden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<footer class=\"elementor-section elementor-top-section elementor-element elementor-element-217b881a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"217b881a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-603a21a8\" data-id=\"603a21a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-461d0031 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"461d0031\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4f2d725e\" data-id=\"4f2d725e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-776d2a31 elementor-widget elementor-widget-heading\" data-id=\"776d2a31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Unternehmen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-440d6ba elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"440d6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/ueber-uns\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00dcber uns<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/impressum\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Impressum<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/presse\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Presse<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-71782c1\" data-id=\"71782c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bf5ad36 elementor-widget elementor-widget-heading\" data-id=\"3bf5ad36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Info<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cc9e8a6 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2cc9e8a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/versand-und-zahlungsbedingungen\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Versand und Zahlungsbedingungen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/agb\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AGB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/privatsphaere-und-datenschutz\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Privatsph\u00e4re &amp; Datenschutz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4c09ce3e\" data-id=\"4c09ce3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3501b0fb elementor-widget elementor-widget-heading\" data-id=\"3501b0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Rechtliches<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fdc097d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7fdc097d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/openthinclient.com\/fr\/rechtliches\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Software<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7b714d19\" data-id=\"7b714d19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6da4cc8a elementor-widget elementor-widget-heading\" data-id=\"6da4cc8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Follow Us<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68accb5 elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"68accb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-9758c9c\" href=\"https:\/\/de-de.facebook.com\/people\/openthinclient-gmbh\/100063657666030\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d550229\" href=\"https:\/\/www.instagram.com\/openthinclient\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-e160b5a\" href=\"https:\/\/de.linkedin.com\/company\/openthinclient-gmbh\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-82b3bad\" href=\"https:\/\/www.youtube.com\/openthinclient%20gmbh\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/footer>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>+49 711 1378636-0 info@openthinclient.com Mo &#8211; Fr: 9:00 &#8211; 18:00 Facebook-f Instagram Linkedin Youtube Jobs Softwareentwickler (m\/w\/d) Ihre Aufgaben Pflege der Distribution &#8220;openthinclient-OS&#8221; basierend auf Debian Administration der Buildsysteme Aktive Teilnahme an der Planung der Software-Entwicklung Ihr Profil Erfahrung in der Softwareentwicklung Praktische Erfahrungen mit Linux und Python Grundkenntnisse in der Administration von Netzwerken und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-798","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jobs - openthinclient<\/title>\n<meta name=\"description\" content=\"Traumjob gef\u00e4llig? Bewerben Sie sich mit nur einem klick.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/openthinclient.com\/fr\/jobs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jobs - openthinclient\" \/>\n<meta property=\"og:description\" content=\"Traumjob gef\u00e4llig? Bewerben Sie sich mit nur einem klick.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/openthinclient.com\/fr\/jobs\/\" \/>\n<meta property=\"og:site_name\" content=\"openthinclient\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063657666030\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T12:07:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/jobs\\\/\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/jobs\\\/\",\"name\":\"Jobs - openthinclient\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#website\"},\"datePublished\":\"2022-04-11T10:53:21+00:00\",\"dateModified\":\"2024-04-24T12:07:09+00:00\",\"description\":\"Traumjob gef\u00e4llig? Bewerben Sie sich mit nur einem klick.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/jobs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/openthinclient.com\\\/jobs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/jobs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/openthinclient.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jobs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#website\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/\",\"name\":\"openthinclient\",\"description\":\"Thin Client Management Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/openthinclient.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#organization\",\"name\":\"openthinclient\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo_openthinclient.png\",\"contentUrl\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo_openthinclient.png\",\"width\":1523,\"height\":235,\"caption\":\"openthinclient\"},\"image\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063657666030\",\"https:\\\/\\\/www.youtube.com\\\/openthinclientgmbh\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/9161909\\\/\",\"https:\\\/\\\/www.instagram.com\\\/openthinclient\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emplois - openthinclient","description":"Envie d'un emploi de r\u00eave ? Postulez en un clic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/openthinclient.com\/fr\/jobs\/","og_locale":"fr_FR","og_type":"article","og_title":"Jobs - openthinclient","og_description":"Traumjob gef\u00e4llig? Bewerben Sie sich mit nur einem klick.","og_url":"https:\/\/openthinclient.com\/fr\/jobs\/","og_site_name":"openthinclient","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063657666030","article_modified_time":"2024-04-24T12:07:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/openthinclient.com\/jobs\/","url":"https:\/\/openthinclient.com\/jobs\/","name":"Emplois - openthinclient","isPartOf":{"@id":"https:\/\/openthinclient.com\/#website"},"datePublished":"2022-04-11T10:53:21+00:00","dateModified":"2024-04-24T12:07:09+00:00","description":"Envie d'un emploi de r\u00eave ? Postulez en un clic.","breadcrumb":{"@id":"https:\/\/openthinclient.com\/jobs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/openthinclient.com\/jobs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/openthinclient.com\/jobs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/openthinclient.com\/"},{"@type":"ListItem","position":2,"name":"Jobs"}]},{"@type":"WebSite","@id":"https:\/\/openthinclient.com\/#website","url":"https:\/\/openthinclient.com\/","name":"openthinclient","description":"Logiciel de gestion des clients l\u00e9gers","publisher":{"@id":"https:\/\/openthinclient.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/openthinclient.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/openthinclient.com\/#organization","name":"openthinclient","url":"https:\/\/openthinclient.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/openthinclient.com\/#\/schema\/logo\/image\/","url":"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient.png","contentUrl":"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient.png","width":1523,"height":235,"caption":"openthinclient"},"image":{"@id":"https:\/\/openthinclient.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063657666030","https:\/\/www.youtube.com\/openthinclientgmbh","https:\/\/www.linkedin.com\/company\/9161909\/","https:\/\/www.instagram.com\/openthinclient\/"]}]}},"_links":{"self":[{"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/comments?post=798"}],"version-history":[{"count":24,"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798\/revisions"}],"predecessor-version":[{"id":33861,"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/pages\/798\/revisions\/33861"}],"wp:attachment":[{"href":"https:\/\/openthinclient.com\/fr\/wp-json\/wp\/v2\/media?parent=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}