{"id":32216,"date":"2023-06-01T12:07:15","date_gmt":"2023-06-01T12:07:15","guid":{"rendered":"https:\/\/openthinclient.com\/?post_type=product&#038;p=32216"},"modified":"2026-04-16T12:57:58","modified_gmt":"2026-04-16T12:57:58","slug":"ram","status":"publish","type":"product","link":"https:\/\/openthinclient.com\/en\/produkt\/arbeitsspeicher\/","title":{"rendered":"RAM"},"content":{"rendered":"<p>openthinclient\u00ae Accessories<\/p>","protected":false},"excerpt":{"rendered":"<p>openthinclient\u00ae Accessories<\/p>","protected":false},"featured_media":32275,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[845],"product_tag":[],"class_list":["post-32216","product","type-product","status-publish","has-post-thumbnail","product_cat-zubehoer-de","desktop-align-left","tablet-align-left","mobile-align-left","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitsspeicher - openthinclient<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/openthinclient.com\/en\/product-2\/ram\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitsspeicher - openthinclient\" \/>\n<meta property=\"og:description\" content=\"openthinclient\u00ae Zubeh\u00f6r\" \/>\n<meta property=\"og:url\" content=\"https:\/\/openthinclient.com\/en\/product-2\/ram\/\" \/>\n<meta property=\"og:site_name\" content=\"openthinclient\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063657666030\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T12:57:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/openthinclient.com\/wp-content\/uploads\/2023\/06\/Arbeitsspeicher.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/\",\"name\":\"Arbeitsspeicher - openthinclient\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Arbeitsspeicher.jpg\",\"datePublished\":\"2023-06-01T12:07:15+00:00\",\"dateModified\":\"2026-04-16T12:57:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Arbeitsspeicher.jpg\",\"contentUrl\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Arbeitsspeicher.jpg\",\"width\":856,\"height\":856},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/produkt\\\/arbeitsspeicher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/openthinclient.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thin Clients Software Vergleich\",\"item\":\"https:\\\/\\\/openthinclient.com\\\/thin-client-software-vergleich\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arbeitsspeicher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#website\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/\",\"name\":\"openthinclient\",\"description\":\"Thin Client Management Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/openthinclient.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#organization\",\"name\":\"openthinclient\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo_openthinclient.png\",\"contentUrl\":\"https:\\\/\\\/openthinclient.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Logo_openthinclient.png\",\"width\":1523,\"height\":235,\"caption\":\"openthinclient\"},\"image\":{\"@id\":\"https:\\\/\\\/openthinclient.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063657666030\",\"https:\\\/\\\/www.youtube.com\\\/openthinclientgmbh\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/9161909\\\/\",\"https:\\\/\\\/www.instagram.com\\\/openthinclient\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RAM - openthinclient","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/openthinclient.com\/en\/product-2\/ram\/","og_locale":"en_GB","og_type":"article","og_title":"Arbeitsspeicher - openthinclient","og_description":"openthinclient\u00ae Zubeh\u00f6r","og_url":"https:\/\/openthinclient.com\/en\/product-2\/ram\/","og_site_name":"openthinclient","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063657666030","article_modified_time":"2026-04-16T12:57:58+00:00","og_image":[{"width":856,"height":856,"url":"https:\/\/openthinclient.com\/wp-content\/uploads\/2023\/06\/Arbeitsspeicher.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/","url":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/","name":"RAM - openthinclient","isPartOf":{"@id":"https:\/\/openthinclient.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/#primaryimage"},"image":{"@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/#primaryimage"},"thumbnailUrl":"https:\/\/openthinclient.com\/wp-content\/uploads\/2023\/06\/Arbeitsspeicher.jpg","datePublished":"2023-06-01T12:07:15+00:00","dateModified":"2026-04-16T12:57:58+00:00","breadcrumb":{"@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/#primaryimage","url":"https:\/\/openthinclient.com\/wp-content\/uploads\/2023\/06\/Arbeitsspeicher.jpg","contentUrl":"https:\/\/openthinclient.com\/wp-content\/uploads\/2023\/06\/Arbeitsspeicher.jpg","width":856,"height":856},{"@type":"BreadcrumbList","@id":"https:\/\/openthinclient.com\/produkt\/arbeitsspeicher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/openthinclient.com\/"},{"@type":"ListItem","position":2,"name":"Thin Clients Software Vergleich","item":"https:\/\/openthinclient.com\/thin-client-software-vergleich\/"},{"@type":"ListItem","position":3,"name":"Arbeitsspeicher"}]},{"@type":"WebSite","@id":"https:\/\/openthinclient.com\/#website","url":"https:\/\/openthinclient.com\/","name":"openthinclient","description":"Thin Client Management Software","publisher":{"@id":"https:\/\/openthinclient.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/openthinclient.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/openthinclient.com\/#organization","name":"openthinclient","url":"https:\/\/openthinclient.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/openthinclient.com\/#\/schema\/logo\/image\/","url":"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient.png","contentUrl":"https:\/\/openthinclient.com\/wp-content\/uploads\/2022\/06\/Logo_openthinclient.png","width":1523,"height":235,"caption":"openthinclient"},"image":{"@id":"https:\/\/openthinclient.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063657666030","https:\/\/www.youtube.com\/openthinclientgmbh","https:\/\/www.linkedin.com\/company\/9161909\/","https:\/\/www.instagram.com\/openthinclient\/"]}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/product\/32216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/media\/32275"}],"wp:attachment":[{"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/media?parent=32216"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/product_brand?post=32216"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/product_cat?post=32216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/openthinclient.com\/en\/wp-json\/wp\/v2\/product_tag?post=32216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}